{"id":368,"date":"2020-05-05T13:02:00","date_gmt":"2020-05-05T11:02:00","guid":{"rendered":"https:\/\/egalitedesterritoires.fr\/?p=368"},"modified":"2024-11-01T10:35:15","modified_gmt":"2024-11-01T09:35:15","slug":"crise-covid-19-revele-etat-reel-pays","status":"publish","type":"post","link":"https:\/\/egalitedesterritoires.fr\/index.php\/2020\/05\/05\/crise-covid-19-revele-etat-reel-pays\/","title":{"rendered":"La crise du COVID-19 r\u00e9v\u00e8le l&rsquo;\u00e9tat r\u00e9el de notre pays"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\n<p>La crise sanitaire actuelle est sans pr\u00e9c\u00e9dent. Nous n&rsquo;avons pas connu pareille situation depuis la grippe espagnole. Beaucoup jugent les gouvernants sur leurs choix politiques. La France ne fait pas exception. Je ne vais pas faire un proc\u00e8s d&rsquo;intention, car il n&rsquo;y a sans doute pas de solution parfaite. Mais je vais tenter de montrer l&rsquo;impact de certains choix politiques r\u00e9alis\u00e9s ces derni\u00e8res ann\u00e9es.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La mamie du Cantal a besoin d&rsquo;internet<\/h2>\n\n\n\n<p>Cette citation de St\u00e9phane Richard, patron d&rsquo;Orange, \u00e9tait une r\u00e9ponse \u00e0 l&rsquo;arriv\u00e9 de Free sur le march\u00e9 du mobile en 2012 :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>Mais<em> tout ne se r\u00e9sume pas \u00e0 un prix ! La mamie du Cantal n&rsquo;a pas besoin de la m\u00eame offre qu&rsquo;un geek \u00e0 Paris.<\/em><\/p><cite>https:\/\/www.lamontagne.fr\/aurillac-15000\/actualites\/mamie-du-cantal-les-propos-du-pdg-dorange-juges-inacceptables_155366\/<\/cite><\/blockquote>\n\n\n\n<p>R\u00e9ponse tr\u00e8s appr\u00e9ci\u00e9e par le pr\u00e9sident du d\u00e9partement cit\u00e9 :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>Le d\u00e9put\u00e9 pointe notamment les clich\u00e9s et le \u00ab<em> raccourci caricatural<\/em> \u00bb de la mamie du Cantal. <\/p><p>Le pr\u00e9sident du Conseil G\u00e9n\u00e9ral du Cantal craint m\u00eame que les propos de St\u00e9phane Richard permettent \u00ab <em>de justifier demain d\u2019une in\u00e9galit\u00e9 de traitement entre les abonn\u00e9s d\u2019Ile-de-France et ceux des territoires ruraux <\/em>\u00bb.<\/p><cite>https:\/\/www.nextinpact.com\/archive\/68096-president-conseil-general-cantal-mamie-stephane-richard.htm<\/cite><\/blockquote>\n\n\n\n<p>Nous sommes en 2020. Le confinement sollicite fortement les infrastructures t\u00e9l\u00e9com, entre t\u00e9l\u00e9travail, \u00e9ducation \u00e0 distance et VoD. Le probl\u00e8me est que les retards et absences de volont\u00e9 de d\u00e9ploiement des op\u00e9rateurs se font sentir dans certaines zones rurales. <a href=\"https:\/\/france3-regions.francetvinfo.fr\/normandie\/orne\/oublies-internet-heure-du-confinement-1812648.html\">L&rsquo;administration d\u00e9mat\u00e9rialis\u00e9e<\/a> y pose probl\u00e8me. Et <a href=\"https:\/\/www.francebleu.fr\/infos\/societe\/limousin-le-confinement-vire-au-cauchemar-pour-les-oublies-d-internet-1586266949\">les \u00ab\u00a0mamies\u00a0\u00bb justement<\/a> ? \u00c9loign\u00e9es de leur famille, <a href=\"https:\/\/www.francebleu.fr\/infos\/societe\/limousin-le-confinement-vire-au-cauchemar-pour-les-oublies-d-internet-1586266949\">une part \u00e2g\u00e9e de la population qui habite dans ces zones rurales<\/a> ne peut pas communiquer avec leurs proches, faute de pouvoir s&rsquo;\u00e9quiper. Finalement, la mamie du Cantal doit pouvoir acc\u00e9der aux m\u00eames services que le geek de Paris, m\u00eame si elle les exploitera moins.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La n\u00e9cessit\u00e9 d&rsquo;une production int\u00e9rieure<\/h2>\n\n\n\n<p>Le fameux d\u00e9bat sur la disponibilit\u00e9 des masques. Globalement, nous avions trop de stocks apr\u00e8s la crise sanitaire de 2009. Nous avons d\u00e9cid\u00e9 de le r\u00e9duire en <strong>arr\u00eatant les commandes<\/strong>. Nous avions une usine en Bretagne. Cette usine a ferm\u00e9, <a href=\"https:\/\/www.franceinter.fr\/comment-la-france-a-sacrifie-sa-principale-usine-de-masques\">faute de commande de l&rsquo;\u00e9tat<\/a>. Nous aurions pu maintenir des commande en quantit\u00e9 r\u00e9duite, afin d&rsquo;assurer une  production minimale, et ne pas laisser p\u00e9rimer le stock actuel. Moralit\u00e9, nous devons commander en urgence, aupr\u00e8s de la Chine, avant que <a href=\"https:\/\/www.lexpress.fr\/actualite\/societe\/une-commande-francaise-de-masques-detournee-vers-les-etats-unis_2122678.html\">les Etats-Unis ne les embarquent sur le tarmac<\/a>, ce qui nous oblige \u00e0 <a href=\"https:\/\/www.liberation.fr\/checknews\/2020\/04\/03\/la-france-a-t-elle-intercepte-des-masques-a-destination-de-la-suede_1784053\">prendre ceux de la Su\u00e8de<\/a>. Une fois arriv\u00e9e sur le sol fran\u00e7ais, <a href=\"https:\/\/www.lejdc.fr\/nevers-58000\/actualites\/nouvelle-requisition-des-masques-commandes-par-la-region-bourgogne-franche-comte_13773937\/\">ils changent parfois de destination \u00e0 la derni\u00e8re minute<\/a>.<\/p>\n\n\n\n<p>A l&rsquo;inverse, beaucoup d&rsquo;entreprises fran\u00e7aises ont pu produire du gel hydro-alcoolique.<a href=\"https:\/\/reporterre.net\/Comment-les-grandes-fortunes-redorent-leur-image-grace-au-coronavirus\"> Ind\u00e9pendamment d&rsquo;un geste \u00ab\u00a0de bonne figure\u00a0\u00bb<\/a>, \u00e7a leur a permis de ne pas suspendre leur activit\u00e9. Elles l&rsquo;ont seulement adapt\u00e9e.<\/p>\n\n\n\n<p>Une production int\u00e9rieure, m\u00eame de faible volume aurait permis de :<\/p>\n\n\n\n<ul><li>R\u00e9pondre plus rapidement aux besoins de notre pays.<\/li><li>Maintenir des emplois qui feront tourner l&rsquo;\u00e9conomie. C&rsquo;\u00e9tait le contenu <a href=\"https:\/\/egalitedesterritoires.fr\/index.php\/2019\/02\/06\/crise-chomage-et-industrie\/\">d&rsquo;un de mes premiers articles<\/a>.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Un syst\u00e8me de sant\u00e9 mis sous pression<\/h2>\n\n\n\n<p>Notre syst\u00e8me de sant\u00e9 est satur\u00e9. Encore faudrait-il ne pas avoir trop mis la pression avant. Nous avons <a href=\"http:\/\/cfecgc-santesocial.fr\/hopitaux-fermeture-lits-suppression-postes\/\">cherch\u00e9 \u00e0 faire des \u00e9conomies dans le secteur de la sant\u00e9<\/a>. Aujourd&rsquo;hui, <a href=\"https:\/\/www.francetvinfo.fr\/sante\/maladie\/coronavirus\/infographie-coronavirus-la-france-compte-moins-de-lits-en-soins-aigus-que-la-moyenne-des-pays-developpes_3876613.html\">nous sommes moins \u00e9quip\u00e9s par habitant que d&rsquo;autres pays<\/a>, qui ont mieux r\u00e9sist\u00e9 que nous.<\/p>\n\n\n\n<p>Encore une fois, la question est celle de la r\u00e9partition territoriale. C&rsquo;est \u00e9vident qu&rsquo;un petit h\u00f4pital ne sera pas pr\u00eat \u00e0 traiter toutes les situations. Mais traiter le premier niveau de criticit\u00e9 au plus pr\u00e8s des habitants reste une n\u00e9cessit\u00e9. Si Apr\u00e8s tout, nous avons bien trait\u00e9 des transferts de patients pendant cette crise.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Nous sommes en guerre, mais nous ne sommes pas pr\u00eats<\/h2>\n\n\n\n<p>Et Bill Gates avait raison. Comme il l&rsquo;expliquait <a href=\"https:\/\/embed.ted.com\/talks\/lang\/fr\/bill_gates_the_next_outbreak_we_re_not_ready\">dans cette vid\u00e9o de 2015<\/a>, nous n&rsquo;\u00e9tions pas pr\u00e9par\u00e9s \u00e0 ce genre de situation. Plus pr\u00e9cis\u00e9ment, les pouvoirs publics de tous les pays occidentaux n&rsquo;ont pas \u00e9valu\u00e9 le risque d&rsquo;une pand\u00e9mie.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Roselyne Bachelot avait-elle tort ?<\/h2>\n\n\n\n<p>Il y a dix ans, la ministre de la sant\u00e9 de l&rsquo;\u00e9poque, Roselyne Bachelot, avait d\u00e9cid\u00e9 de sortir l&rsquo;artillerie lourde afin de se pr\u00e9parer contre l&rsquo;\u00e9pid\u00e9mie de \u00ab\u00a0Grippe A\u00a0\u00bb. En pleine crise financi\u00e8re, l&rsquo;opinion politique avait consid\u00e9r\u00e9 cette op\u00e9ration comme une gabegie financi\u00e8re. R\u00e9trospectivement, si le sc\u00e9nario avait pris la forme actuelle, l&rsquo;aurait-on  bl\u00e2m\u00e9e de cette d\u00e9pense face aux cons\u00e9quences \u00e9conomiques que nous allons devoir subir aujourd&rsquo;hui ?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La crise sanitaire actuelle est sans pr\u00e9c\u00e9dent. Nous n&rsquo;avons pas connu pareille situation depuis la grippe espagnole. Beaucoup jugent les gouvernants sur leurs choix politiques. La France ne fait pas exception. Je ne vais pas faire un proc\u00e8s d&rsquo;intention, car il n&rsquo;y a sans doute pas de solution parfaite. Mais je vais tenter de montrer &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/egalitedesterritoires.fr\/index.php\/2020\/05\/05\/crise-covid-19-revele-etat-reel-pays\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;La crise du COVID-19 r\u00e9v\u00e8le l&rsquo;\u00e9tat r\u00e9el de notre pays&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,21],"tags":[3,20],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La crise du COVID-19 r\u00e9v\u00e8le l&#039;\u00e9tat r\u00e9el de notre pays - Egalit\u00e9 des territoires<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/egalitedesterritoires.fr\/index.php\/2020\/05\/05\/crise-covid-19-revele-etat-reel-pays\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La crise du COVID-19 r\u00e9v\u00e8le l&#039;\u00e9tat r\u00e9el de notre pays - Egalit\u00e9 des territoires\" \/>\n<meta property=\"og:description\" content=\"La crise sanitaire actuelle est sans pr\u00e9c\u00e9dent. Nous n&rsquo;avons pas connu pareille situation depuis la grippe espagnole. Beaucoup jugent les gouvernants sur leurs choix politiques. La France ne fait pas exception. Je ne vais pas faire un proc\u00e8s d&rsquo;intention, car il n&rsquo;y a sans doute pas de solution parfaite. Mais je vais tenter de montrer &hellip; Continuer la lecture de &laquo;&nbsp;La crise du COVID-19 r\u00e9v\u00e8le l&rsquo;\u00e9tat r\u00e9el de notre pays&nbsp;&raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/egalitedesterritoires.fr\/index.php\/2020\/05\/05\/crise-covid-19-revele-etat-reel-pays\/\" \/>\n<meta property=\"og:site_name\" content=\"Egalit\u00e9 des territoires\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-05T11:02:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-01T09:35:15+00:00\" \/>\n<meta name=\"author\" content=\"Editeur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editeur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/egalitedesterritoires.fr\/index.php\/2020\/05\/05\/crise-covid-19-revele-etat-reel-pays\/\",\"url\":\"https:\/\/egalitedesterritoires.fr\/index.php\/2020\/05\/05\/crise-covid-19-revele-etat-reel-pays\/\",\"name\":\"La crise du COVID-19 r\u00e9v\u00e8le l'\u00e9tat r\u00e9el de notre pays - Egalit\u00e9 des territoires\",\"isPartOf\":{\"@id\":\"https:\/\/egalitedesterritoires.fr\/#website\"},\"datePublished\":\"2020-05-05T11:02:00+00:00\",\"dateModified\":\"2024-11-01T09:35:15+00:00\",\"author\":{\"@id\":\"https:\/\/egalitedesterritoires.fr\/#\/schema\/person\/c36fa3038a178a95f1a68d8ea0eef776\"},\"breadcrumb\":{\"@id\":\"https:\/\/egalitedesterritoires.fr\/index.php\/2020\/05\/05\/crise-covid-19-revele-etat-reel-pays\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/egalitedesterritoires.fr\/index.php\/2020\/05\/05\/crise-covid-19-revele-etat-reel-pays\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/egalitedesterritoires.fr\/index.php\/2020\/05\/05\/crise-covid-19-revele-etat-reel-pays\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/egalitedesterritoires.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La crise du COVID-19 r\u00e9v\u00e8le l&rsquo;\u00e9tat r\u00e9el de notre pays\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/egalitedesterritoires.fr\/#website\",\"url\":\"https:\/\/egalitedesterritoires.fr\/\",\"name\":\"Egalit\u00e9 des territoires\",\"description\":\"Les fran\u00e7ais sont tous \u00e9gaux, mais pas partout en France\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/egalitedesterritoires.fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/egalitedesterritoires.fr\/#\/schema\/person\/c36fa3038a178a95f1a68d8ea0eef776\",\"name\":\"Editeur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/egalitedesterritoires.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b110c3c1599e47518a2d0e0d47ad44f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b110c3c1599e47518a2d0e0d47ad44f1?s=96&d=mm&r=g\",\"caption\":\"Editeur\"},\"url\":\"https:\/\/egalitedesterritoires.fr\/index.php\/author\/editeur\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La crise du COVID-19 r\u00e9v\u00e8le l'\u00e9tat r\u00e9el de notre pays - Egalit\u00e9 des territoires","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/egalitedesterritoires.fr\/index.php\/2020\/05\/05\/crise-covid-19-revele-etat-reel-pays\/","og_locale":"fr_FR","og_type":"article","og_title":"La crise du COVID-19 r\u00e9v\u00e8le l'\u00e9tat r\u00e9el de notre pays - Egalit\u00e9 des territoires","og_description":"La crise sanitaire actuelle est sans pr\u00e9c\u00e9dent. Nous n&rsquo;avons pas connu pareille situation depuis la grippe espagnole. Beaucoup jugent les gouvernants sur leurs choix politiques. La France ne fait pas exception. Je ne vais pas faire un proc\u00e8s d&rsquo;intention, car il n&rsquo;y a sans doute pas de solution parfaite. Mais je vais tenter de montrer &hellip; Continuer la lecture de &laquo;&nbsp;La crise du COVID-19 r\u00e9v\u00e8le l&rsquo;\u00e9tat r\u00e9el de notre pays&nbsp;&raquo;","og_url":"https:\/\/egalitedesterritoires.fr\/index.php\/2020\/05\/05\/crise-covid-19-revele-etat-reel-pays\/","og_site_name":"Egalit\u00e9 des territoires","article_published_time":"2020-05-05T11:02:00+00:00","article_modified_time":"2024-11-01T09:35:15+00:00","author":"Editeur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Editeur","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/egalitedesterritoires.fr\/index.php\/2020\/05\/05\/crise-covid-19-revele-etat-reel-pays\/","url":"https:\/\/egalitedesterritoires.fr\/index.php\/2020\/05\/05\/crise-covid-19-revele-etat-reel-pays\/","name":"La crise du COVID-19 r\u00e9v\u00e8le l'\u00e9tat r\u00e9el de notre pays - Egalit\u00e9 des territoires","isPartOf":{"@id":"https:\/\/egalitedesterritoires.fr\/#website"},"datePublished":"2020-05-05T11:02:00+00:00","dateModified":"2024-11-01T09:35:15+00:00","author":{"@id":"https:\/\/egalitedesterritoires.fr\/#\/schema\/person\/c36fa3038a178a95f1a68d8ea0eef776"},"breadcrumb":{"@id":"https:\/\/egalitedesterritoires.fr\/index.php\/2020\/05\/05\/crise-covid-19-revele-etat-reel-pays\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/egalitedesterritoires.fr\/index.php\/2020\/05\/05\/crise-covid-19-revele-etat-reel-pays\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/egalitedesterritoires.fr\/index.php\/2020\/05\/05\/crise-covid-19-revele-etat-reel-pays\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/egalitedesterritoires.fr\/"},{"@type":"ListItem","position":2,"name":"La crise du COVID-19 r\u00e9v\u00e8le l&rsquo;\u00e9tat r\u00e9el de notre pays"}]},{"@type":"WebSite","@id":"https:\/\/egalitedesterritoires.fr\/#website","url":"https:\/\/egalitedesterritoires.fr\/","name":"Egalit\u00e9 des territoires","description":"Les fran\u00e7ais sont tous \u00e9gaux, mais pas partout en France","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/egalitedesterritoires.fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/egalitedesterritoires.fr\/#\/schema\/person\/c36fa3038a178a95f1a68d8ea0eef776","name":"Editeur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/egalitedesterritoires.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b110c3c1599e47518a2d0e0d47ad44f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b110c3c1599e47518a2d0e0d47ad44f1?s=96&d=mm&r=g","caption":"Editeur"},"url":"https:\/\/egalitedesterritoires.fr\/index.php\/author\/editeur\/"}]}},"_links":{"self":[{"href":"https:\/\/egalitedesterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts\/368"}],"collection":[{"href":"https:\/\/egalitedesterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/egalitedesterritoires.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/egalitedesterritoires.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/egalitedesterritoires.fr\/index.php\/wp-json\/wp\/v2\/comments?post=368"}],"version-history":[{"count":5,"href":"https:\/\/egalitedesterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts\/368\/revisions"}],"predecessor-version":[{"id":382,"href":"https:\/\/egalitedesterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts\/368\/revisions\/382"}],"wp:attachment":[{"href":"https:\/\/egalitedesterritoires.fr\/index.php\/wp-json\/wp\/v2\/media?parent=368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/egalitedesterritoires.fr\/index.php\/wp-json\/wp\/v2\/categories?post=368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/egalitedesterritoires.fr\/index.php\/wp-json\/wp\/v2\/tags?post=368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}