{"id":14,"count":5,"description":"","link":"https:\/\/egalitedesterritoires.fr\/index.php\/category\/transparence-vie-publique\/","name":"Transparence de la vie publique","slug":"transparence-vie-publique","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Archives des Transparence de la vie publique - Egalit\u00e9 des territoires<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/egalitedesterritoires.fr\/index.php\/category\/transparence-vie-publique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Transparence de la vie publique - Egalit\u00e9 des territoires\" \/>\n<meta property=\"og:url\" content=\"https:\/\/egalitedesterritoires.fr\/index.php\/category\/transparence-vie-publique\/\" \/>\n<meta property=\"og:site_name\" content=\"Egalit\u00e9 des territoires\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/egalitedesterritoires.fr\/index.php\/category\/transparence-vie-publique\/\",\"url\":\"https:\/\/egalitedesterritoires.fr\/index.php\/category\/transparence-vie-publique\/\",\"name\":\"Archives des Transparence de la vie publique - Egalit\u00e9 des territoires\",\"isPartOf\":{\"@id\":\"https:\/\/egalitedesterritoires.fr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/egalitedesterritoires.fr\/index.php\/category\/transparence-vie-publique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/egalitedesterritoires.fr\/index.php\/category\/transparence-vie-publique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/egalitedesterritoires.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transparence de la vie publique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/egalitedesterritoires.fr\/#website\",\"url\":\"https:\/\/egalitedesterritoires.fr\/\",\"name\":\"Egalit\u00e9 des territoires\",\"description\":\"Les fran\u00e7ais sont tous \u00e9gaux, mais pas partout en France\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/egalitedesterritoires.fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Transparence de la vie publique - Egalit\u00e9 des territoires","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/egalitedesterritoires.fr\/index.php\/category\/transparence-vie-publique\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des Transparence de la vie publique - Egalit\u00e9 des territoires","og_url":"https:\/\/egalitedesterritoires.fr\/index.php\/category\/transparence-vie-publique\/","og_site_name":"Egalit\u00e9 des territoires","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/egalitedesterritoires.fr\/index.php\/category\/transparence-vie-publique\/","url":"https:\/\/egalitedesterritoires.fr\/index.php\/category\/transparence-vie-publique\/","name":"Archives des Transparence de la vie publique - Egalit\u00e9 des territoires","isPartOf":{"@id":"https:\/\/egalitedesterritoires.fr\/#website"},"breadcrumb":{"@id":"https:\/\/egalitedesterritoires.fr\/index.php\/category\/transparence-vie-publique\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/egalitedesterritoires.fr\/index.php\/category\/transparence-vie-publique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/egalitedesterritoires.fr\/"},{"@type":"ListItem","position":2,"name":"Transparence de la vie publique"}]},{"@type":"WebSite","@id":"https:\/\/egalitedesterritoires.fr\/#website","url":"https:\/\/egalitedesterritoires.fr\/","name":"Egalit\u00e9 des territoires","description":"Les fran\u00e7ais sont tous \u00e9gaux, mais pas partout en France","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/egalitedesterritoires.fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/egalitedesterritoires.fr\/index.php\/wp-json\/wp\/v2\/categories\/14"}],"collection":[{"href":"https:\/\/egalitedesterritoires.fr\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/egalitedesterritoires.fr\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/egalitedesterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts?categories=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}